{"id":873,"count":25,"description":"","link":"https:\/\/wefapress.com\/en\/category\/news-en\/","name":"News","slug":"news-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Newsroom from Wefapress\u00ae | News, events and trade fairs<\/title>\n<meta name=\"description\" content=\"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wefapress.com\/en\/category\/news-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archive\" \/>\n<meta property=\"og:description\" content=\"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wefapress.com\/en\/category\/news-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Wefapress\u00ae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/category\\\/news-en\\\/\",\"url\":\"https:\\\/\\\/wefapress.com\\\/en\\\/category\\\/news-en\\\/\",\"name\":\"Newsroom from Wefapress\u00ae | News, events and trade fairs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#website\"},\"description\":\"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/category\\\/news-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/category\\\/news-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wefapress.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wefapress.com\\\/en\\\/\",\"name\":\"Wefapress\u00ae\",\"description\":\"Pionier in der PE-Verarbeitung\",\"publisher\":{\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wefapress.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#organization\",\"name\":\"Wefapress\u00ae\",\"url\":\"https:\\\/\\\/wefapress.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wefapress.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/wefapress-logo.svg\",\"contentUrl\":\"https:\\\/\\\/wefapress.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/wefapress-logo.svg\",\"width\":243,\"height\":78,\"caption\":\"Wefapress\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/wefapress.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wefapress\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/wefapress\",\"https:\\\/\\\/www.instagram.com\\\/wefapress\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Wefapress\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Newsroom from Wefapress\u00ae | News, events and trade fairs","description":"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wefapress.com\/en\/category\/news-en\/","og_locale":"en_US","og_type":"article","og_title":"News Archive","og_description":"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!","og_url":"https:\/\/wefapress.com\/en\/category\/news-en\/","og_site_name":"Wefapress\u00ae","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wefapress.com\/en\/category\/news-en\/","url":"https:\/\/wefapress.com\/en\/category\/news-en\/","name":"Newsroom from Wefapress\u00ae | News, events and trade fairs","isPartOf":{"@id":"https:\/\/wefapress.com\/en\/#website"},"description":"The Wefapress\u00ae newsroom | Latest news \u2713 Trends \u2713 and exciting insights from our company \u27a4 Find out more!","breadcrumb":{"@id":"https:\/\/wefapress.com\/en\/category\/news-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wefapress.com\/en\/category\/news-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wefapress.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/wefapress.com\/en\/#website","url":"https:\/\/wefapress.com\/en\/","name":"Wefapress\u00ae","description":"Pionier in der PE-Verarbeitung","publisher":{"@id":"https:\/\/wefapress.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wefapress.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wefapress.com\/en\/#organization","name":"Wefapress\u00ae","url":"https:\/\/wefapress.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wefapress.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wefapress.com\/wp-content\/uploads\/2023\/06\/wefapress-logo.svg","contentUrl":"https:\/\/wefapress.com\/wp-content\/uploads\/2023\/06\/wefapress-logo.svg","width":243,"height":78,"caption":"Wefapress\u00ae"},"image":{"@id":"https:\/\/wefapress.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wefapress\/","https:\/\/de.linkedin.com\/company\/wefapress","https:\/\/www.instagram.com\/wefapress\/","https:\/\/www.youtube.com\/user\/Wefapress"]}]}},"_links":{"self":[{"href":"https:\/\/wefapress.com\/en\/wp-json\/wp\/v2\/categories\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wefapress.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/wefapress.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/wefapress.com\/en\/wp-json\/wp\/v2\/posts?categories=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}